{"id":3010,"date":"2025-10-04T06:40:13","date_gmt":"2025-10-04T06:40:13","guid":{"rendered":"https:\/\/www.markus-schall.de\/?p=3010"},"modified":"2026-04-27T16:51:43","modified_gmt":"2026-04-27T16:51:43","slug":"quand-le-devoir-redevient-obligatoire-une-sorte-dessai-de-monsieur-von-loreot","status":"publish","type":"post","link":"https:\/\/www.markus-schall.de\/fr\/2025\/10\/quand-le-devoir-redevient-obligatoire-une-sorte-dessai-de-monsieur-von-loreot\/","title":{"rendered":"Quand le devoir redevient obligation. Une sorte d'essai de Monsieur de L'oreot."},"content":{"rendered":"<h2>Consid\u00e9rations sur un \u00e9ventuel retour du service militaire obligatoire<\/h2>\n<p>Une sorte d'essai de M. de L'oreot sur un possible <a title=\"Quelles sont les cons\u00e9quences de la tension en Allemagne ?\" href=\"https:\/\/www.markus-schall.de\/fr\/2025\/10\/que-signifie-la-tension-en-allemagne-et-quelles-en-seraient-les-consequences-concretes\/\">Chute de tension<\/a>. <!--more--><\/p>\n<hr \/>\n<h2>Derni\u00e8res actualit\u00e9s sur le sujet<\/h2>\n<p><strong>27.04.2026<\/strong>: Un lecteur des NachDenkSeiten a r\u00e9cemment fait parler de lui : <a href=\"https:\/\/www.nachdenkseiten.de\/?p=149520\" target=\"_blank\" rel=\"noopener\"><strong>\u00c0 91 ans, il s'est port\u00e9 volontaire pour le service de r\u00e9serve.<\/strong><\/a> - y compris une r\u00e9f\u00e9rence \u00e0 une \u201ev\u00e9ritable exp\u00e9rience du front\u201c de la Seconde Guerre mondiale et une description remarquablement sobre de ce que signifie r\u00e9ellement la guerre. Ce qui devait \u00eatre une r\u00e9action satirique au d\u00e9bat sur l'augmentation des limites d'\u00e2ge pour les r\u00e9servistes se lit comme un document d'une extr\u00eame gravit\u00e9 :<\/p>\n<p>Les nuits de bombardement, la faim, la perte - et la douce question de savoir si l'on souhaite vraiment y retourner. Ou si on doit le faire.<\/p>\n<p>Pour M. von L'oreot, l'affaire devrait \u00eatre d\u00e9finitivement close : Lorsque le devoir redevient une obligation, il suffit apparemment d'un robuste nonag\u00e9naire pour mettre en \u00e9vidence l'absurdit\u00e9 de la situation. Et alors que l'on r\u00e9fl\u00e9chit encore ailleurs \u00e0 des \u201emod\u00e8les flexibles\u201c, cette lettre fournit un rappel nettement moins flexible, mais d'autant plus percutant, de ce que signifie r\u00e9ellement la guerre.<\/p>\n<hr \/>\n<h2>Chapitre I : Un appel inattendu<\/h2>\n<p>C'\u00e9tait un mardi. Ou un mercredi. Je n'en suis plus s\u00fbr. Je me souviens seulement d'un thermos de caf\u00e9 filtre, d'un sandwich \u00e0 la saucisse de foie - et d'un appel t\u00e9l\u00e9phonique.<\/p>\n<blockquote><p><em>\"Bonjour, c'est le centre de carri\u00e8re de la Bundeswehr qui vous parle ! Vous \u00eates pr\u00e9s\u00e9lectionn\u00e9 pour \u00eatre r\u00e9engag\u00e9. R\u00e9activation de la conscription. Vous comprenez\".<\/em><\/p><\/blockquote>\n<p><a title=\"Service militaire : Refuser le service de guerre\" href=\"https:\/\/www.markus-schall.de\/fr\/2025\/09\/droit-a-la-guerre-refus-du-service-militaire-ce-quil-faut-faire-en-cas-durgence\/\">Centre de carri\u00e8re ? Arm\u00e9e f\u00e9d\u00e9rale ?<\/a> Je n'ai tout d'abord rien compris. Je m'\u00e9tais en effet habitu\u00e9 \u00e0 une vie dans laquelle les gens me laissaient tranquille tant que je ne les provoquais pas. Une vie avec de l'eau chaude, des avis d'imposition calcul\u00e9s et une certaine aversion int\u00e9rieure pour les courses en for\u00eat avec des bottes en caoutchouc.<\/p>\n<p>Je devais donc \u00e0 nouveau \u00eatre \u201esaisi\u201c. Pas au sens spirituel, mais apparemment tr\u00e8s concr\u00e8tement - nominativement, physiquement et, le cas \u00e9ch\u00e9ant, avec des bagages de temp\u00eate.<\/p>\n<p>La dame au bout du fil \u00e9tait aimable. Presque trop aimable. Le genre de gentillesse qui vous fait chercher instinctivement une issue de secours.<\/p>\n<blockquote><p>\"Il ne s'agit dans un premier temps que d'une mesure de la pr\u00e9structure de recensement de la pr\u00e9paration \u00e0 la d\u00e9fense nationale\".<\/p><\/blockquote>\n<p>J'ai demand\u00e9 qu'on me le r\u00e9p\u00e8te. La dame a soupir\u00e9 et a relu le mot, cette fois-ci dans un lent allemand de fonctionnaire.<\/p>\n<p>Je l'ai consciencieusement not\u00e9 sur une liste de courses, entre \"dentifrice\" et \"g\u00e2teau \u00e0 la cr\u00e8me\". Cela me semblait d'une importance comparable.<\/p>\n<h2>Chapitre II : Les devoirs de l'\u00c9tat et le devoir du citoyen<\/h2>\n<p>Dans une Allemagne id\u00e9ale - c'est-\u00e0-dire une Allemagne o\u00f9 il n'y a jamais de moutarde et o\u00f9 le voisin ne joue pas au souffleur de feuilles - il existe une division du travail claire :<\/p>\n<ul>\n<li>L'\u00c9tat <strong>prot\u00e8ge<\/strong>, le citoyen <strong>paie<\/strong>.<\/li>\n<li>L'\u00c9tat <strong>annonce<\/strong>, le citoyen <strong>acquiesce<\/strong>.<\/li>\n<li>L'\u00c9tat <strong>oblige<\/strong> - et le citoyen <strong>met ses chaussures<\/strong>.<\/li>\n<\/ul>\n<p>C'est un syst\u00e8me d'une clart\u00e9 rassurante. Jusqu'au moment o\u00f9 l'on est soi-m\u00eame concern\u00e9.<\/p>\n<blockquote><p><em>\"Il faut \u00eatre pr\u00eat\"<\/em>a-t-on dit.<br \/>\n<em>\"C'est possible\"<\/em>, a-t-on ajout\u00e9.<br \/>\nEt <em>\"L'obligation s'applique \u00e0 tous\", a-t-il ajout\u00e9.<\/em><\/p><\/blockquote>\n<p>On m'a assur\u00e9 que tout se passerait de mani\u00e8re tr\u00e8s humaine. Il ne s'agissait pas d'un exercice, mais d'un \"engagement citoyen\". Je me suis souvenu de ma derni\u00e8re exp\u00e9rience d'engagement citoyen : un agent \u00e9lectoral qui m'avait demand\u00e9 de ne pas \u00e9mietter les biscuits au beurre lors du d\u00e9pouillement.<\/p>\n<p>Maintenant donc, \u00e0 plus grande \u00e9chelle. Un service obligatoire. Service \u00e0 la soci\u00e9t\u00e9.<\/p>\n<p>Je m'imaginais une sorte de jardinage moderne. Avec un uniforme.<\/p>\n<p>En m\u00eame temps, je me suis souvenu de ce principe que j'avais appris en cours de biologie :<\/p>\n<blockquote><p><em>\"Si on ne s'entra\u00eene pas pendant longtemps, il ne faut pas s'attendre \u00e0 des performances\".<\/em><\/p><\/blockquote>\n<p>J'ai d\u00e9cid\u00e9, par pr\u00e9caution, de ne pas promettre de prestation.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-3021\" src=\"https:\/\/www.markus-schall.de\/wp-content\/uploads\/loreot-pflicht-uniform-garten.jpg\" alt=\"Monsieur de L&#039;oreot \u00e0 la Bundeswehr\" width=\"1024\" height=\"683\" srcset=\"https:\/\/www.markus-schall.de\/wp-content\/uploads\/loreot-pflicht-uniform-garten.jpg 1024w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/loreot-pflicht-uniform-garten-300x200.jpg 300w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/loreot-pflicht-uniform-garten-768x512.jpg 768w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/loreot-pflicht-uniform-garten-18x12.jpg 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Plus tard dans la soir\u00e9e, \u00e0 la maison<\/p>\n<h2>Chapitre III : Les m\u00e9dias - l'animateur sans r\u00e9gie<\/h2>\n<p>Le retour du service militaire obligatoire est un sujet s\u00e9rieux.<\/p>\n<p>Un tr\u00e8s s\u00e9rieux.<\/p>\n<p>Tellement s\u00e9rieux qu'il est difficile de le confier \u00e0 quelqu'un de s\u00e9rieux. C'est pourquoi - comme toujours dans les affaires s\u00e9rieuses - c'est \u00e0 lui de prendre le relais. <strong>la t\u00e9l\u00e9vision<\/strong>.<\/p>\n<p>Dans le discours public, cela s'exprime de la mani\u00e8re suivante :<\/p>\n<p>Un jeune pr\u00e9sentateur en veste slim est assis en face d'un ministre dont la coiffure semble avoir \u00e9t\u00e9 valid\u00e9e par les services de protection de la Constitution.<\/p>\n<p>Entre les deux, une table avec un verre d'eau - \u00e0 moiti\u00e9 plein ou \u00e0 moiti\u00e9 vide, selon la situation s\u00e9curitaire.<\/p>\n<p>Le pr\u00e9sentateur commence :<\/p>\n<blockquote><p><em>\"Monsieur le ministre, \u00e0 quel point la situation est-elle dangereuse alors que vous envisagez maintenant la conscription ?\"<\/em><\/p><\/blockquote>\n<p>Le ministre r\u00e9pond :<\/p>\n<blockquote><p><em>\"Nous ne pensons pas \u00e0 la conscription. Nous pensons \u00e0 la s\u00e9curit\u00e9\".<\/em><\/p><\/blockquote>\n<p>L'animateur acquiesce.<\/p>\n<p>La cam\u00e9ra fait un zoom avant.<\/p>\n<p>Le verre n'est pas touch\u00e9.<\/p>\n<p>A ce stade, le studio affiche le mot \u201eEXCLUSIF\u201c - alors que les m\u00eames phrases ont d\u00e9j\u00e0 \u00e9t\u00e9 prononc\u00e9es dans cinq autres formats. Mais l\u00e0, elles s'appelaient \u201eSondersendung\u201c, \u201eHintergrund\u201c ou \u201eKlartext\u201c - selon l'identit\u00e9 de la cha\u00eene et les couleurs du tapis roulant.<\/p>\n<p>La visualisation m\u00e9diatique du \"retour au devoir civique\" est particuli\u00e8rement remarquable :<\/p>\n<p>Nous voyons des images d'archives de jeunes hommes en maillot de corps en train de faire leur lit, suivies de gros plans de chars en train de faire demi-tour dans des gravi\u00e8res.<\/p>\n<p>Le tout accompagn\u00e9 d'une musique dramatique, quelque part entre la sc\u00e8ne de crime et la d\u00e9mo techno.<\/p>\n<p>Une voix off - chaleureuse, masculine, favorable \u00e0 l'\u00c9tat - explique<\/p>\n<blockquote><p>\"Il ne s'agit pas de guerre. Il s'agit de responsabilit\u00e9\".<\/p><\/blockquote>\n<p>Dans ces moments-l\u00e0, je me demande s'il est possible de faire la guerre en \u00e9tant responsable.<\/p>\n<p>Ou la responsabilit\u00e9 sans la guerre.<\/p>\n<p>Ou la guerre sans voix off.<\/p>\n<p>Dans un talk-show en fin de soir\u00e9e, une journaliste demande<\/p>\n<blockquote><p><em>\"Mais les jeunes sont-ils encore pr\u00eats \u00e0 s'engager aujourd'hui ?\"<\/em><\/p><\/blockquote>\n<p>Un jeune homme avec un sweat \u00e0 capuche et des lunettes r\u00e9pond :<\/p>\n<blockquote><p><em>\"Je n'ai pas d'opinion. Mais j'ai un sentiment\".<\/em><\/p><\/blockquote>\n<p>Un professeur \u00e2g\u00e9 et barbu - gracieux, mais imbuvable - r\u00e9torque :<\/p>\n<blockquote><p><em>\"Dans ma g\u00e9n\u00e9ration, le sens du devoir faisait partie de la soupe !\"<\/em><\/p><\/blockquote>\n<p>Tout le monde rit poliment.<\/p>\n<p>L'\u00e9mission se termine par un<\/p>\n<blockquote><p><em>\u201eC'est tout pour aujourd'hui - restez vigilant\u201c,<\/em><\/p><\/blockquote>\n<p>tandis que la musique du g\u00e9n\u00e9rique de fin de la ZDF retentit en arri\u00e8re-plan - probablement compos\u00e9e par quelqu'un qui \u00e9tait d\u00e9j\u00e0 vigilant en 1984.<\/p>\n<p>Personnellement, pour ce genre de format, j'ai toujours une th\u00e9i\u00e8re \u00e0 port\u00e9e de main. Elle ne me prot\u00e8ge pas de la conscription, mais elle m'\u00e9vite de mordre l'\u00e9cran pr\u00e9matur\u00e9ment.<\/p>\n<p>Car ce que les m\u00e9dias tentent d'emp\u00eacher, ce n'est pas l'obligation elle-m\u00eame - mais son explication.<\/p>\n<p>Et si on regarde assez longtemps, on se rend compte que<\/p>\n<p>La tension du reportage est \u00e9lastique.<\/p>\n<p>Il s'\u00e9tend largement -<\/p>\n<p>mais il atteint rarement sa cible.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-3022\" src=\"https:\/\/www.markus-schall.de\/wp-content\/uploads\/loreot-pflicht-fernseher.jpg\" alt=\"L&#039;oreot et la t\u00e9l\u00e9vision\" width=\"1024\" height=\"683\" srcset=\"https:\/\/www.markus-schall.de\/wp-content\/uploads\/loreot-pflicht-fernseher.jpg 1024w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/loreot-pflicht-fernseher-300x200.jpg 300w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/loreot-pflicht-fernseher-768x512.jpg 768w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/loreot-pflicht-fernseher-18x12.jpg 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h2>Chapitre IV : Les citoyens pris en \u00e9tau par le devoir<\/h2>\n<p><strong>Une soir\u00e9e patriotique en cinq actes<\/strong><\/p>\n<h3>\ud83e\uddcd 1. l'homme comme nombre<\/h3>\n<p>Tout d'abord, le citoyen est un \u00eatre humain.<\/p>\n<p>Du moins, c'\u00e9tait le cas jusqu'\u00e0 pr\u00e9sent.<\/p>\n<p>Mais depuis que l'on reparle de plus en plus du service militaire obligatoire - c'est-\u00e0-dire du retour solennel de l'individu dans la bo\u00eete pliante de la d\u00e9fense collective du pays -, la perception a chang\u00e9.<\/p>\n<blockquote><p><em>\u201eM\u00fcller, Karl, n\u00e9 en 1988 - utilisable dans le groupe de soutien 7b (logistique, en fauteuil roulant)\u201c.\u201c<\/em><\/p><\/blockquote>\n<p>On ne vous demande donc plus votre avis :<\/p>\n<blockquote><p><em>\"Qu'est-ce que vous faites particuli\u00e8rement bien ?\"<\/em><\/p><\/blockquote>\n<p>Mais plut\u00f4t<\/p>\n<blockquote><p><em>\"Qu'est-ce qui serait le moins acceptable pour vous ?\"<\/em><\/p><\/blockquote>\n<h3>\ud83d\udccb 2. la saisie - en douceur, mais fermement<\/h3>\n<p>La saisie moderne se fait sans papier.<br \/>\nPar mail, application ou code QR.<\/p>\n<p>On re\u00e7oit une \"convocation num\u00e9rique\" et on peut y remplir si on se sent capable de porter un masque \u00e0 gaz en cas d'urgence.<\/p>\n<p>Si ce n'est pas le cas, le formulaire propose tout de m\u00eame des alternatives :<\/p>\n<blockquote><p><em>\"Je sais bien beurrer les petits pains (pour 80 personnes maximum)\".<\/em><br \/>\n<em>\"Je poss\u00e8de un porte-bloc et je sais le tenir\".<\/em><br \/>\n<em>\"J'\u00e9tais dans l'arm\u00e9e allemande dans les ann\u00e9es 90, mais je ne me souviens que du goulasch\".<\/em><\/p><\/blockquote>\n<p>Celui qui le remplit correctement se voit automatiquement attribuer une forme de d\u00e9fense :<\/p>\n<p>activement, semi-passivement, ou en apportant un soutien moral (colonne de commentaires sur Internet).<\/p>\n<h3>\ud83d\udecf 3. le r\u00e9am\u00e9nagement de l'habitat<\/h3>\n<p>Une fois que le citoyen est enregistr\u00e9, les modifications suivent. Par exemple, il re\u00e7oit<\/p>\n<ul>\n<li>un sac en tissu orange avec l'inscription : <strong>\"Quand \u00e7a commence, vous \u00eates le premier \u00e0 le savoir\".<\/strong><\/li>\n<li>une invitation \u00e0 la r\u00e9union d'orientation au centre communal B, salle 6 (en passant par la salle des \u00e9quipements, puis \u00e0 gauche). Du th\u00e9 sera servi, mais uniquement si le thermos de l'entrep\u00f4t de la protection civile fonctionne.<\/li>\n<li>une fiche d'information sur le stockage correct de la p\u00e2te \u00e0 tartiner en cas d'alerte \u00e9lev\u00e9e. On y lit notamment <strong>\"La margarine n'est pas un mat\u00e9riau de protection\".<\/strong><\/li>\n<\/ul>\n<h3>\ud83d\udea8 4. la question de contr\u00f4le : puis-je encore dire \"non\" ?<\/h3>\n<p>De nombreux citoyens se demandent : \"Dois-je le faire ?\" La r\u00e9ponse est<\/p>\n<blockquote><p><em><strong>\u201eNon - sauf dans le cas o\u00f9 vous devez le faire\u201c.\u201c<\/strong><\/em><\/p><\/blockquote>\n<p>C'est rassurant.<\/p>\n<p>Car cela montre qu'il existe encore des possibilit\u00e9s de choix - mais seulement entre les options :<\/p>\n<ul>\n<li>\"Engagement volontaire\"<\/li>\n<li>\"Volontariat obligatoire\"<\/li>\n<li>ou \"contribution volontaire obligatoire dans le cadre d'une situation d'arbitrage orient\u00e9e vers le service (forme abr\u00e9g\u00e9e : obligation)\".<\/li>\n<\/ul>\n<p>Ceux qui s'y opposent sont consid\u00e9r\u00e9s comme n'\u00e9tant pas pr\u00eats \u00e0 s'int\u00e9grer, ce qu'il ne faut toutefois pas confondre avec la r\u00e9ticence \u00e0 s'int\u00e9grer - un terme exclusivement utilis\u00e9 dans les exercices d'entra\u00eenement \u00e0 la politique \u00e9trang\u00e8re.<\/p>\n<h3>\ud83e\udde6 5. la r\u00e9sistance s'organise - en silence<\/h3>\n<p>Un homme de ma connaissance - appelons-le Monsieur Dobermann - a r\u00e9cemment d\u00e9clar\u00e9 qu'en cas d'incorporation, il se r\u00e9fugierait sous la table du salon. En l'interrogeant, il s'est av\u00e9r\u00e9 qu'il l'occupait d\u00e9j\u00e0 avant, car il ne voulait pas discuter d'ampoules \u00e0 \u00e9conomie d'\u00e9nergie avec sa femme.<\/p>\n<p>Il serait donc pr\u00e9par\u00e9.<\/p>\n<p>Son chien porte d\u00e9j\u00e0 une casquette de campagne.<\/p>\n<h3>\ud83d\udcdc Conclusion : il faut de l'ordre - m\u00eame si personne ne sait pourquoi<\/h3>\n<p>Le citoyen, disait-on autrefois, est la colonne vert\u00e9brale de la d\u00e9mocratie.<br \/>\nAujourd'hui, il n'est souvent plus qu'un num\u00e9ro de t\u00e9l\u00e9phone dans un tableau Excel de l'\u00c9tat, sous l'onglet \"Mobilisation : civile\".<\/p>\n<p>Et pourtant, il y a de l'espoir. Car tant que les gens \u00e9criront sur du papier tandis que les tablettes tomberont en panne, tant que la salade de pommes de terre sera consid\u00e9r\u00e9e comme une r\u00e9serve de crise et tant qu'un citoyen responsable se demandera s'il l\u00e8ve d'abord la gauche ou l'autre en marchant -<\/p>\n<p>...tant qu'il y a des gens qui gardent un peu d'humour m\u00eame dans le devoir.<\/p>\n<p>Et \u00e7a, Mesdames et Messieurs, c'est la vraie colonne vert\u00e9brale.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-3023\" src=\"https:\/\/www.markus-schall.de\/wp-content\/uploads\/loreot-pflicht-hund-feldmuetze.jpg\" alt=\"Monsieur Dobermann avec chien et casquette de campagne\" width=\"1024\" height=\"683\" srcset=\"https:\/\/www.markus-schall.de\/wp-content\/uploads\/loreot-pflicht-hund-feldmuetze.jpg 1024w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/loreot-pflicht-hund-feldmuetze-300x200.jpg 300w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/loreot-pflicht-hund-feldmuetze-768x512.jpg 768w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/loreot-pflicht-hund-feldmuetze-18x12.jpg 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h2>Chapitre V : Entre le mot et l'effet - l'art du contr\u00f4le<\/h2>\n<h3>\ud83d\udcfa Les mots, les mots, l'inefficacit\u00e9<\/h3>\n<p>A une \u00e9poque o\u00f9 des mots comme \"r\u00e9silience\", \"mobilisation\" ou \"soci\u00e9t\u00e9 de service\" sont port\u00e9s avec un s\u00e9rieux de plus en plus serein \u00e0 travers les journaux t\u00e9l\u00e9vis\u00e9s du soir, il est frappant de constater que l'on ne peut pas se contenter d'un simple \"oui\" :<\/p>\n<p>Plus personne ne demande ce que cela signifie exactement.<\/p>\n<blockquote><p>\u201eLa r\u00e9silience\u201c, c'est aujourd'hui, quand la pression monte -<br \/>\net que le citoyen n'\u00e9clate pas pour autant.<\/p><\/blockquote>\n<p>Pendant ce temps, les autorit\u00e9s expliquent dans un clair langage officiel qu'elles ne pr\u00e9voient pas d'obligation d'obligation, mais qu'elles se contentent de v\u00e9rifier s'il faut v\u00e9rifier, comme elles le feraient s'il fallait v\u00e9rifier.<\/p>\n<p>Le citoyen - entre la machine \u00e0 caf\u00e9 et le plan d'\u00e9conomie d'\u00e9nergie - \u00e9coute.<br \/>\nIl acquiesce.<br \/>\nIl ne comprend pas.<br \/>\nMais il sent que quelque chose se pr\u00e9pare.<\/p>\n<h3>\ud83e\udde9 L'astuce de la langue<\/h3>\n<p>Loriot aurait dit<\/p>\n<blockquote><p><em>\u201eC'est comme la dinde de No\u00ebl - on la farcit d'abord, on l'assaisonne ensuite, puis on dit : maintenant, on la met dans le tube, mais personne n'a jamais demand\u00e9 si elle avait \u00e9t\u00e9 invit\u00e9e\u201c.\u201c<\/em><\/p><\/blockquote>\n<p>C'est ainsi que fonctionne le langage des mesures pr\u00e9paratoires :<\/p>\n<ul>\n<li>Les \"structures pr\u00e9ventives\" sont ce que l'on appelait autrefois les \"pr\u00e9alertes\".<\/li>\n<li>Le \"devoir civique assoupli\" \u00e9tait autrefois le \"service militaire\".<\/li>\n<li>\"Participation n\u00e9cessaire dans le cadre de la stabilit\u00e9 de la soci\u00e9t\u00e9\" signifiait auparavant : \"Restez tranquille, M\u00fcller\".<\/li>\n<\/ul>\n<p>Ce qui est coul\u00e9 aujourd'hui dans des paragraphes \u00e9tait hier encore une id\u00e9e de table des habitu\u00e9s et ne sera demain \"plus discutable\".<\/p>\n<h3>\ud83e\udde0 Le contr\u00f4le ne commence pas avec les uniformes<\/h3>\n<p>Le v\u00e9ritable contr\u00f4le ne commence pas avec l'ordre de marche.<br \/>\nElle commence bien avant :<\/p>\n<ul>\n<li>sur le site <strong>Vocabulaire<\/strong> lors de la conf\u00e9rence de presse,<\/li>\n<li>\u00e0 la <strong>Ordre des cha\u00eenes<\/strong> \u00e0 la t\u00e9l\u00e9vision d'\u00c9tat,<\/li>\n<li>\u00e0 la <strong>Tonalit\u00e9 de la voix<\/strong>La notion de \"responsabilit\u00e9 individuelle\" semble soudain proche de l'\u00c9tat.<\/li>\n<\/ul>\n<p>C'est l'art de cr\u00e9er, par les mots, un climat dans lequel la contrainte ne ressemble plus \u00e0 une contrainte - mais \u00e0 un \u201esentiment de devoir\u201c.<\/p>\n<p>Ou pire encore : comme \"raison\".<\/p>\n<h3>\ud83c\udfbb Le citoyen comme musique de fond<\/h3>\n<p>Pendant que tout cela se passe, le citoyen reste poli. Il remplit des formulaires, donne son avis sur des enqu\u00eates en ligne et clique sur la croix :<\/p>\n<p><strong>\"J'ai lu et compris les instructions sur la capacit\u00e9 de mobilisation\".<\/strong><\/p>\n<p>Bien s\u00fbr, il n'a rien compris.<\/p>\n<p>Mais il esp\u00e8re qu'on le laissera ensuite tranquille.<br \/>\nL'\u00c9tat, qui se pr\u00e9pare, le rassure :<\/p>\n<blockquote><p><em>\"Ne vous inqui\u00e9tez pas, cela ne concerne que tr\u00e8s peu de personnes. La plupart ne remarquent rien\".<\/em><\/p><\/blockquote>\n<p>La plupart des gens ne remarquent vraiment rien.<br \/>\nMais comme chacun sait, les choses changent rapidement.<\/p>\n<div class=\"lyte-wrapper\" style=\"width:640px;max-width:100%;margin:5px;\"><div class=\"lyMe\" id=\"WYL_1fkm82pOybE\"><div id=\"lyte_1fkm82pOybE\" data-src=\"https:\/\/www.markus-schall.de\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2F1fkm82pOybE%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/1fkm82pOybE\" rel=\"nofollow noopener\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.markus-schall.de\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2F1fkm82pOybE%2F0.jpg\" alt=\"Vignette de la vid\u00e9o YouTube\" width=\"640\" height=\"340\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:640px;margin:5px;\"><\/div><br \/>\nVicco von B\u00fclow en interview en 1979 (source : <a href=\"https:\/\/www.butenunbinnen.de\/videos\/loriot-dreinachneun-vicco-von-buelow-zeitreise-100.html\" target=\"_blank\" rel=\"noopener\">Radio Br\u00eame<\/a>)<\/p>\n<h2>\ud83d\udd6f\ufe0f Conclusion : une invitation \u00e0 la r\u00e9flexion<\/h2>\n<p>Si vous avez lu ce texte jusqu'ici, je tiens \u00e0 vous remercier. Non pas parce que vous \u00eates devenus plus intelligents - je ne peux pas le promettre - mais parce que vous \u00eates devenus plus intelligents.<\/p>\n<p>mais parce que vous vous \u00eates arr\u00eat\u00e9s pour r\u00e9fl\u00e9chir \u00e0 quelque chose qui n'appara\u00eet habituellement que dans des formules d'actualit\u00e9 ou des projets de loi.<\/p>\n<blockquote><p>L'obligation n'est pas le probl\u00e8me.<br \/>\nL'inconscience avec laquelle elle pourrait \u00eatre r\u00e9introduite l'est.<\/p><\/blockquote>\n<p>Autrefois, on disait<\/p>\n<blockquote><p><em>\"D\u00e9fense de commencer\".<\/em><\/p><\/blockquote>\n<p>Aujourd'hui, on dit<\/p>\n<blockquote><p>\"Veuillez cliquer sur 'Accepter'\".<\/p><\/blockquote>\n<p>La question n'est pas de savoir si le service militaire obligatoire est une bonne ou une mauvaise chose. Il s'agit plut\u00f4t de savoir si nous savons encore ce que nous soutenons en nous taisant.<\/p>\n<p>Et si nous pouvons encore faire la diff\u00e9rence entre l'\u00c9tat qui prot\u00e8ge et l'\u00c9tat qui s'immisce - et qui reste.<\/p>\n<blockquote><p>Peut-\u00eatre qu'en 2025, le devoir de citoyen consistera \u00e0 ne pas imm\u00e9diatement <em>\"Oui\"<\/em> de dire quelque chose. Mais de demander d'abord :<\/p>\n<p><em>\"Pour quoi faire exactement ?\"<\/em><br \/>\nEt <em>\u201eA qui cela profite-t-il - et \u00e0 qui cela ne profite-t-il pas ?\u201c<\/em><\/p><\/blockquote>\n<p>Ceux qui le font ne marchent pas.<br \/>\nMais il pense - et cela a toujours \u00e9t\u00e9 la forme de r\u00e9sistance la plus dangereuse.<\/p>\n<p>Avec mes salutations oblig\u00e9es et r\u00e9serv\u00e9es<br \/>\nde l'impossibilit\u00e9 du silence<\/p>\n<p>Votre ma\u00eetre de L'oreot<\/p>\n<hr \/>\n<h3>Ce que nos grands-p\u00e8res ont racont\u00e9 de la guerre<\/h3>\n<p><a href=\"https:\/\/www.markus-schall.de\/fr\/2026\/01\/ce-que-nos-grands-peres-racontaient-de-la-guerre-et-pourquoi-ces-voix-manquent-aujourdhui\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-4678\" src=\"https:\/\/www.markus-schall.de\/wp-content\/uploads\/Opa-Kriegserinnerungen-300x200.jpg\" alt=\"M\u00e9moires de guerre des grands-p\u00e8res\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.markus-schall.de\/wp-content\/uploads\/Opa-Kriegserinnerungen-300x200.jpg 300w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/Opa-Kriegserinnerungen-768x512.jpg 768w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/Opa-Kriegserinnerungen-18x12.jpg 18w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/Opa-Kriegserinnerungen.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Si vous vous demandez pourquoi un homme de 91 ans peut aujourd'hui en dire plus sur la guerre en quelques phrases que de nombreuses tables rondes r\u00e9unies, vous trouverez une r\u00e9ponse possible dans un autre article du magazine : dans <a href=\"https:\/\/www.markus-schall.de\/fr\/2026\/01\/ce-que-nos-grands-peres-racontaient-de-la-guerre-et-pourquoi-ces-voix-manquent-aujourdhui\/\"><em><strong>\u201eCe que nos grands-p\u00e8res ont racont\u00e9 de la guerre - et pourquoi ces voix manquent aujourd'hui\u201c<\/strong><\/em><\/a> il appara\u00eet clairement que ces exp\u00e9riences n'ont jamais \u00e9t\u00e9 transmises \u00e0 voix haute, jamais id\u00e9ologiquement et souvent par fragments. Il ne s'agissait pas de grands discours, mais de petites sc\u00e8nes - des souvenirs de hasard, de peur, de survie et de ce qu'il vaut mieux ne pas r\u00e9p\u00e9ter. Ce sont pr\u00e9cis\u00e9ment ces voix silencieuses qui disparaissent avec le temps, et avec elles une forme de r\u00e9alit\u00e9 qui ne peut pas \u00eatre remplac\u00e9e par des mod\u00e8les ou des documents strat\u00e9giques. Cela explique peut-\u00eatre aussi pourquoi beaucoup de choses semblent aujourd'hui si abstraites : Parce qu'il manque ceux qui savaient encore que la guerre n'est pas un concept, mais un \u00e9tat qui transforme les gens - souvent pendant toute une vie. Et que, dans la mesure du possible, il vaut mieux ne pas la commencer du tout.<\/p>\n<h2>Avenir avec chargeur - Monsieur de L'oreot ach\u00e8te un scooter \u00e9lectrique<\/h2>\n<p><a href=\"https:\/\/www.markus-schall.de\/fr\/2025\/10\/lavenir-avec-un-chargeur-monsieur-von-loreot-achete-un-scooter-electrique\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-3019\" src=\"https:\/\/www.markus-schall.de\/wp-content\/uploads\/loereot-e-scooter-1.jpg\" alt=\"Un appel inattendu\" width=\"150\" height=\"100\" \/><\/a><a href=\"https:\/\/www.markus-schall.de\/fr\/2025\/10\/lavenir-avec-un-chargeur-monsieur-von-loreot-achete-un-scooter-electrique\/\"><strong>Monsieur de L'oreot commande un scooter \u00e9lectrique<\/strong><\/a> - et rencontre le polystyr\u00e8ne, le temps de charge et la r\u00e9alit\u00e9. Une histoire pleine d'humour sur la mobilit\u00e9 \u00e9lectrique, les visites \u00e0 la boulangerie et la petite ironie du quotidien - sur 750 m\u00e8tres. Apr\u00e8s : Th\u00e9, chemin\u00e9e et une discr\u00e8te prise de conscience.<\/p>\n<hr \/>\n\n\t\t\t<div class=\"display-post-types\">\n\n\t\t\t\t\t\t\t<style type=\"text\/css\">\n\t\t\t#dpt-wrapper-574 { --dpt-text-align: left;--dpt-image-crop: center;--dpt-border-radius: 5px;--dpt-h-gutter: 10px;--dpt-v-gutter: 9px; }\t\t\t<\/style>\n\t\t\t<style type=\"text\/css\">#dpt-wrapper-574 { --dpt-title-font-style:normal;--dpt-title-font-weight:600;--dpt-title-line-height:1.5;--dpt-title-text-decoration:none;--dpt-title-text-transform:none;--dpt-excerpt-font-style:normal;--dpt-excerpt-font-weight:400;--dpt-excerpt-line-height:1.5;--dpt-excerpt-text-decoration:none;--dpt-excerpt-text-transform:none;--dpt-meta1-font-style:normal;--dpt-meta1-font-weight:400;--dpt-meta1-line-height:1.9;--dpt-meta1-text-decoration:none;--dpt-meta1-text-transform:none;--dpt-meta2-font-style:normal;--dpt-meta2-font-weight:400;--dpt-meta2-line-height:1.9;--dpt-meta2-text-decoration:none;--dpt-meta2-text-transform:none; }<\/style><div class=\"dpt-main-header\">\n\t\t\t\t\t\t<div class=\"dpt-main-title\">\n\t\t\t\t\t\t\t<span class=\"dpt-main-title-text\">Derniers articles sur Art &amp; Culture<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\t\t\t\n\t\t\t\t<div id=\"dpt-wrapper-574\" class=\"dpt-wrapper dpt-mag1 land1 dpt-cropped dpt-flex-wrap\" >\n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"dpt-entry has-thumbnail\" data-title=\"wie war syrien vor dem krieg? wer regiert heute? was bedeutet das f\u00fcr gefl\u00fcchtete in deutschland?\" data-id=\"4628\"  data-category=\"allgemein gesellschaft kunst &amp; kultur\" data-post_tag=\"deutschland europa geopolitik krisen meinungsfreiheit sicherheitspolitik\">\n\t\t\t\t\t\t\t<div class=\"dpt-entry-wrapper\"><div class=\"dpt-featured-content\"><div class=\"dpt-permalink\"><a href=\"https:\/\/www.markus-schall.de\/fr\/2026\/01\/comment-etait-la-syrie-avant-la-guerre-qui-gouverne-aujourdhui-que-cela-signifie-t-il-pour-les-refugies-en-allemagne\/\" class=\"dpt-permalink\"><span class=\"screen-reader-text\">Comment \u00e9tait la Syrie avant la guerre ? Qui gouverne aujourd'hui ? Qu'est-ce que cela signifie pour les personnes qui ont fui en Allemagne ?<\/span><\/a><\/div><div class=\"dpt-thumbnail\"><div class=\"dpt-thumbnail-inner\"><img width=\"1024\" height=\"683\" class=\"attachment-full size-full\" alt=\"La Syrie et Damas\" context=\"dpt\" data-dpt-src=\"https:\/\/www.markus-schall.de\/wp-content\/uploads\/Syrien-Damaskus.jpg\" data-dpt-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-dpt-srcset=\"https:\/\/www.markus-schall.de\/wp-content\/uploads\/Syrien-Damaskus.jpg 1024w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/Syrien-Damaskus-300x200.jpg 300w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/Syrien-Damaskus-768x512.jpg 768w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/Syrien-Damaskus-18x12.jpg 18w\" \/><\/div><span class=\"dpt-thumbnail-aspect-ratio\" style=\"padding-top: 75%\"><\/span><\/div><\/div><div class=\"sub-entry\"><h3 class=\"dpt-title\"><a class=\"dpt-title-link\" href=\"https:\/\/www.markus-schall.de\/fr\/2026\/01\/comment-etait-la-syrie-avant-la-guerre-qui-gouverne-aujourdhui-que-cela-signifie-t-il-pour-les-refugies-en-allemagne\/\" rel=\"bookmark\">Comment \u00e9tait la Syrie avant la guerre ? Qui gouverne aujourd'hui ? Qu'est-ce que cela signifie pour les personnes qui ont fui en Allemagne ?<\/a><\/h3><\/div><\/div>\n\t\t\t\t\t\t<\/div><!-- .dpt-entry -->\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"dpt-entry has-thumbnail\" data-title=\"apple im wandel: fr\u00fche ger\u00e4te, eigene erfahrungen und eine ausstellung im ocm\" data-id=\"5480\"  data-category=\"allgemein apple iphone &amp; ipad apple macos hardware kunst &amp; kultur stories &amp; humor\" data-post_tag=\"apple erfahrungen filemaker mac prozesse publishing\">\n\t\t\t\t\t\t\t<div class=\"dpt-entry-wrapper\"><div class=\"dpt-featured-content\"><div class=\"dpt-permalink\"><a href=\"https:\/\/www.markus-schall.de\/fr\/2026\/03\/apple-en-mutation-les-premiers-appareils-experiences-personnelles-et-une-exposition-a-locm\/\" class=\"dpt-permalink\"><span class=\"screen-reader-text\">Apple en mutation : premiers appareils, exp\u00e9riences personnelles et une exposition \u00e0 l'OCM<\/span><\/a><\/div><div class=\"dpt-thumbnail\"><div class=\"dpt-thumbnail-inner\"><img width=\"1024\" height=\"683\" class=\"attachment-full size-full\" alt=\"Apple Macintosh Classic et Color Classic\" context=\"dpt\" data-dpt-src=\"https:\/\/www.markus-schall.de\/wp-content\/uploads\/Apple-OCM-Titel.jpg\" data-dpt-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-dpt-srcset=\"https:\/\/www.markus-schall.de\/wp-content\/uploads\/Apple-OCM-Titel.jpg 1024w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/Apple-OCM-Titel-300x200.jpg 300w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/Apple-OCM-Titel-768x512.jpg 768w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/Apple-OCM-Titel-18x12.jpg 18w\" \/><\/div><span class=\"dpt-thumbnail-aspect-ratio\" style=\"padding-top: 75%\"><\/span><\/div><\/div><div class=\"sub-entry\"><h3 class=\"dpt-title\"><a class=\"dpt-title-link\" href=\"https:\/\/www.markus-schall.de\/fr\/2026\/03\/apple-en-mutation-les-premiers-appareils-experiences-personnelles-et-une-exposition-a-locm\/\" rel=\"bookmark\">Apple en mutation : premiers appareils, exp\u00e9riences personnelles et une exposition \u00e0 l'OCM<\/a><\/h3><\/div><\/div>\n\t\t\t\t\t\t<\/div><!-- .dpt-entry -->\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"dpt-entry has-thumbnail\" data-title=\"ulrike gu\u00e9rot: eine europ\u00e4erin zwischen idee, universit\u00e4t und \u00f6ffentlichem diskurs\" data-id=\"4039\"  data-category=\"allgemein gesellschaft kunst &amp; kultur\" data-post_tag=\"denkmodelle deutschland europa geopolitik krisen meinungsfreiheit portrait sicherheitspolitik spieltheorie\">\n\t\t\t\t\t\t\t<div class=\"dpt-entry-wrapper\"><div class=\"dpt-featured-content\"><div class=\"dpt-permalink\"><a href=\"https:\/\/www.markus-schall.de\/fr\/2025\/12\/ulrike-guerot-une-europeenne-entre-lidee-duniversite-et-le-discours-public\/\" class=\"dpt-permalink\"><span class=\"screen-reader-text\">Ulrike Gu\u00e9rot : une europ\u00e9enne entre id\u00e9e, universit\u00e9 et discours public<\/span><\/a><\/div><div class=\"dpt-thumbnail\"><div class=\"dpt-thumbnail-inner\"><img width=\"1024\" height=\"683\" class=\"attachment-full size-full\" alt=\"Ulrike Gu\u00e9rot et l&#039;Europe\" context=\"dpt\" data-dpt-src=\"https:\/\/www.markus-schall.de\/wp-content\/uploads\/ulrike-guerot-portrait.jpg\" data-dpt-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-dpt-srcset=\"https:\/\/www.markus-schall.de\/wp-content\/uploads\/ulrike-guerot-portrait.jpg 1024w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/ulrike-guerot-portrait-300x200.jpg 300w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/ulrike-guerot-portrait-768x512.jpg 768w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/ulrike-guerot-portrait-18x12.jpg 18w\" \/><\/div><span class=\"dpt-thumbnail-aspect-ratio\" style=\"padding-top: 75%\"><\/span><\/div><\/div><div class=\"sub-entry\"><h3 class=\"dpt-title\"><a class=\"dpt-title-link\" href=\"https:\/\/www.markus-schall.de\/fr\/2025\/12\/ulrike-guerot-une-europeenne-entre-lidee-duniversite-et-le-discours-public\/\" rel=\"bookmark\">Ulrike Gu\u00e9rot : une europ\u00e9enne entre id\u00e9e, universit\u00e9 et discours public<\/a><\/h3><\/div><\/div>\n\t\t\t\t\t\t<\/div><!-- .dpt-entry -->\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"dpt-entry has-thumbnail\" data-title=\"die krimtataren &#8211; geschichte, herkunft und gegenwart eines vergessenen volkes\" data-id=\"4154\"  data-category=\"allgemein gesellschaft kunst &amp; kultur\" data-post_tag=\"europa geopolitik krisen meinungsfreiheit\">\n\t\t\t\t\t\t\t<div class=\"dpt-entry-wrapper\"><div class=\"dpt-featured-content\"><div class=\"dpt-permalink\"><a href=\"https:\/\/www.markus-schall.de\/fr\/2025\/12\/les-tatars-de-crimee-lhistoire-lorigine-et-le-present-dun-peuple-oublie\/\" class=\"dpt-permalink\"><span class=\"screen-reader-text\">Les Tatars de Crim\u00e9e - histoire, origine et pr\u00e9sent d'un peuple oubli\u00e9<\/span><\/a><\/div><div class=\"dpt-thumbnail\"><div class=\"dpt-thumbnail-inner\"><img width=\"1024\" height=\"683\" class=\"attachment-full size-full\" alt=\"Steppe tartare de Crim\u00e9e\" context=\"dpt\" data-dpt-src=\"https:\/\/www.markus-schall.de\/wp-content\/uploads\/Krimtartaren-Steppe.jpg\" data-dpt-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-dpt-srcset=\"https:\/\/www.markus-schall.de\/wp-content\/uploads\/Krimtartaren-Steppe.jpg 1024w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/Krimtartaren-Steppe-300x200.jpg 300w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/Krimtartaren-Steppe-768x512.jpg 768w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/Krimtartaren-Steppe-18x12.jpg 18w\" \/><\/div><span class=\"dpt-thumbnail-aspect-ratio\" style=\"padding-top: 75%\"><\/span><\/div><\/div><div class=\"sub-entry\"><h3 class=\"dpt-title\"><a class=\"dpt-title-link\" href=\"https:\/\/www.markus-schall.de\/fr\/2025\/12\/les-tatars-de-crimee-lhistoire-lorigine-et-le-present-dun-peuple-oublie\/\" rel=\"bookmark\">Les Tatars de Crim\u00e9e - histoire, origine et pr\u00e9sent d'un peuple oubli\u00e9<\/a><\/h3><\/div><\/div>\n\t\t\t\t\t\t<\/div><!-- .dpt-entry -->\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n<hr \/>\n<h2>Foire aux questions (FAQ)<\/h2>\n<ol>\n<li><strong>Que signifie le cas de tension en Allemagne et quelles en seraient les cons\u00e9quences ?<\/strong><br \/>\nVoir l'article sur un \u00e9ventuel <strong><a href=\"https:\/\/www.markus-schall.de\/fr\/2025\/10\/que-signifie-la-tension-en-allemagne-et-quelles-en-seraient-les-consequences-concretes\/\">Cas de tension en Allemagne<\/a><\/strong><\/li>\n<li><strong>Comment puis-je agir et puis-je refuser un \u00e9ventuel service militaire ?<\/strong><br \/>\nVoir l'article sur <strong><a href=\"https:\/\/www.markus-schall.de\/fr\/2025\/09\/droit-a-la-guerre-refus-du-service-militaire-ce-quil-faut-faire-en-cas-durgence\/\">Conscription et objection de conscience<\/a><\/strong><\/li>\n<li><strong>Est-ce une obligation l\u00e9gale de tenir un petit pain de saucisse de foie dans la main lors de la convocation ?<\/strong><br \/>\nSeulement si l'on affiche \u00e0 cette occasion une expression l\u00e9g\u00e8rement confuse et que l'on contacte le minist\u00e8re des thermos. Sinon, une tranche de saucisse de chasse suffit aussi.<\/li>\n<li><strong>Mon Dobermann peut-il me dispenser du service militaire s'il porte d\u00e9j\u00e0 la casquette de l'arm\u00e9e allemande ?<\/strong><br \/>\nUniquement s'il est prouv\u00e9 que le chien a suivi une formation de base et des cours d'instruction militaire - de pr\u00e9f\u00e9rence en Basse-Saxe.<\/li>\n<li><strong>Dois-je accorder l'asile \u00e0 mon voisin s'il s'est retranch\u00e9 sous la table, arm\u00e9 d'ampoules \u00e0 \u00e9conomie d'\u00e9nergie ?<\/strong><br \/>\nPas n\u00e9cessairement. Il est toutefois recommand\u00e9 de lui glisser sous la table une nouvelle ampoule de 100 watts et un journal quotidien de 1982.<\/li>\n<li><strong>Comment puis-je savoir si l'appel est un v\u00e9ritable avis de conscription ou si c'est juste mon beau-fr\u00e8re qui s'ennuie ?<\/strong><br \/>\nLes v\u00e9ritables avis de conscription arrivent en principe dans une enveloppe qui sent l\u00e9g\u00e8rement la choucroute et qui porte la mention \u201eConfidentiel - Bundeswe(h)r's !.<\/li>\n<li><strong>L'obligation s'applique-t-elle aussi dans le thermos ou seulement en dehors ?<\/strong><br \/>\nSelon l'article 12, paragraphe 3, de l'ordonnance sur les obligations de 1958, le contenu du thermos est laiss\u00e9 \u00e0 la discr\u00e9tion de son d\u00e9tenteur, \u00e0 condition que celui-ci ait termin\u00e9 son service civil en bonne et due forme avec la cuill\u00e8re.<\/li>\n<li><strong>Et si le ministre \u00e0 la t\u00e9l\u00e9vision ressemblait \u00e0 une visite chez le dentiste qui a \u00e9t\u00e9 report\u00e9e ?<\/strong><br \/>\nDans ce cas, il est urgent d'\u00e9teindre la t\u00e9l\u00e9vision, de fermer les rideaux et de mettre une vid\u00e9o de Loriot tir\u00e9e des archives. Une autre solution consiste \u00e0 regarder tranquillement par la fen\u00eatre.<\/li>\n<li><strong>Si l'obligation redevient obligatoire - puis-je aussi envoyer ma d\u00e9claration d'imp\u00f4t avec la r\u00e8gle ?<\/strong><br \/>\nSeulement si la r\u00e8gle est conforme \u00e0 la norme DIN et qu'elle est sign\u00e9e par le pr\u00e9fet des finances. Sinon, vous risquez un redressement fiscal au poids papier.<\/li>\n<li><strong>Que faire si mon salon ressemble de plus en plus \u00e0 une base de la D\u00e9fense territoriale ?<\/strong><br \/>\nTransf\u00e9rez toutes les situations de conversation dans la salle de bain et menez les d\u00e9bats exclusivement avec un bonnet de bain. C'est un signe de d\u00e9termination.<\/li>\n<li><strong>Dois-je informer ma femme de chaque avis de conscription ?<\/strong><br \/>\nNon, vous pouvez aussi retourner la bo\u00eete de saucisses de foie \u00e0 la place. Selon le protocole familial de 1973, cela est consid\u00e9r\u00e9 comme une communication indirecte d'une importance strat\u00e9gique sup\u00e9rieure.<\/li>\n<li><strong>Pourquoi le chien portait-il la casquette et pas l'homme ?<\/strong><br \/>\nParce que dans de nombreux cas, les chiens atteignent plus rapidement le grade de caporal, surtout par vent d'ouest. Les hommes, en revanche, doivent tondre la pelouse au moins trois fois pour y parvenir.<\/li>\n<li><strong>Puis-je jouer du tuba au lieu de porter un fusil lorsque je fais mon service militaire ?<\/strong><br \/>\nOui - pour autant que vous puissiez interpr\u00e9ter sans faute le chant de marche \u201eWir lagen vor Madagaskar\u201c \u00e0 l'envers au tuba. Au pas de charge, bien s\u00fbr.<\/li>\n<li><strong>Est-il permis de documenter le devoir obligatoire dans un cahier des charges ?<\/strong><br \/>\nTout \u00e0 fait. Les cahiers des charges sont m\u00eame obligatoires \u00e0 partir du quatri\u00e8me niveau obligatoire. Ils ne peuvent toutefois \u00eatre \u00e9crits qu'avec des stylos \u00e0 bille provenant des stocks de la Bundeswehr.<\/li>\n<li><strong>Comment se comporter correctement lorsque la t\u00e9l\u00e9vision commence \u00e0 mentir, mais que ma saucisse de foie est d\u00e9j\u00e0 entam\u00e9e ?<\/strong><br \/>\nFinissez d'abord de m\u00e2cher. Ensuite, asseyez-vous ostensiblement de c\u00f4t\u00e9 par rapport \u00e0 la t\u00e9l\u00e9vision, marmonnez \"Oh l\u00e0 l\u00e0 !\" et passez en mode arr\u00eat sur image.<\/li>\n<li><strong>Puis-je donner une gifle au pr\u00e9sentateur \u00e0 la t\u00e9l\u00e9vision, m\u00eame si je ne suis que spectateur ?<\/strong><br \/>\nUniquement de mani\u00e8re symbolique - en tapotant l\u00e9g\u00e8rement sur l'\u00e9cran avec un vieil exemplaire de magazine t\u00e9l\u00e9vis\u00e9 datant de 2023. Tout autre geste serait impoli et potentiellement asocial.<\/li>\n<\/ol>\n<hr \/>\n\n\t\t\t<div class=\"display-post-types\">\n\n\t\t\t\t\t\t\t<style type=\"text\/css\">\n\t\t\t#dpt-wrapper-575 { --dpt-text-align: left;--dpt-image-crop: center;--dpt-border-radius: 5px;--dpt-h-gutter: 10px;--dpt-v-gutter: 9px; }\t\t\t<\/style>\n\t\t\t<style type=\"text\/css\">#dpt-wrapper-575 { --dpt-title-font-style:normal;--dpt-title-font-weight:600;--dpt-title-line-height:1.5;--dpt-title-text-decoration:none;--dpt-title-text-transform:none;--dpt-excerpt-font-style:normal;--dpt-excerpt-font-weight:400;--dpt-excerpt-line-height:1.5;--dpt-excerpt-text-decoration:none;--dpt-excerpt-text-transform:none;--dpt-meta1-font-style:normal;--dpt-meta1-font-weight:400;--dpt-meta1-line-height:1.9;--dpt-meta1-text-decoration:none;--dpt-meta1-text-transform:none;--dpt-meta2-font-style:normal;--dpt-meta2-font-weight:400;--dpt-meta2-line-height:1.9;--dpt-meta2-text-decoration:none;--dpt-meta2-text-transform:none; }<\/style><div class=\"dpt-main-header\">\n\t\t\t\t\t\t<div class=\"dpt-main-title\">\n\t\t\t\t\t\t\t<span class=\"dpt-main-title-text\">Th\u00e8mes de soci\u00e9t\u00e9 contemporains<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\t\t\t\n\t\t\t\t<div id=\"dpt-wrapper-575\" class=\"dpt-wrapper dpt-mag1 land1 dpt-cropped dpt-flex-wrap\" >\n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"dpt-entry has-thumbnail\" data-title=\"wie ich in vier monaten f\u00fcnf b\u00fccher in zwei sprachen geschrieben habe\" data-id=\"2775\"  data-category=\"allgemein b\u00fccher gesellschaft tipps &amp; anleitungen\" data-post_tag=\"buch digitales eigentum lernen prozesse publishing verlag\">\n\t\t\t\t\t\t\t<div class=\"dpt-entry-wrapper\"><div class=\"dpt-featured-content\"><div class=\"dpt-permalink\"><a href=\"https:\/\/www.markus-schall.de\/fr\/2025\/09\/comment-jai-ecrit-cinq-livres-en-deux-langues-en-quatre-mois\/\" class=\"dpt-permalink\"><span class=\"screen-reader-text\">Comment j'ai \u00e9crit cinq livres en deux langues en quatre mois<\/span><\/a><\/div><div class=\"dpt-thumbnail\"><div class=\"dpt-thumbnail-inner\"><img width=\"1920\" height=\"1280\" class=\"attachment-full size-full\" alt=\"\u00c9crire des livres avec Affinity et BoD\" context=\"dpt\" data-dpt-src=\"https:\/\/www.markus-schall.de\/wp-content\/uploads\/buecher-affinity-bod-selfpublishing.jpg\" data-dpt-sizes=\"(max-width: 1920px) 100vw, 1920px\" data-dpt-srcset=\"https:\/\/www.markus-schall.de\/wp-content\/uploads\/buecher-affinity-bod-selfpublishing.jpg 1920w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/buecher-affinity-bod-selfpublishing-300x200.jpg 300w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/buecher-affinity-bod-selfpublishing-1024x683.jpg 1024w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/buecher-affinity-bod-selfpublishing-768x512.jpg 768w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/buecher-affinity-bod-selfpublishing-1536x1024.jpg 1536w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/buecher-affinity-bod-selfpublishing-18x12.jpg 18w\" \/><\/div><span class=\"dpt-thumbnail-aspect-ratio\" style=\"padding-top: 75%\"><\/span><\/div><\/div><div class=\"sub-entry\"><h3 class=\"dpt-title\"><a class=\"dpt-title-link\" href=\"https:\/\/www.markus-schall.de\/fr\/2025\/09\/comment-jai-ecrit-cinq-livres-en-deux-langues-en-quatre-mois\/\" rel=\"bookmark\">Comment j'ai \u00e9crit cinq livres en deux langues en quatre mois<\/a><\/h3><\/div><\/div>\n\t\t\t\t\t\t<\/div><!-- .dpt-entry -->\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"dpt-entry has-thumbnail\" data-title=\"cloud-act, datenhoheit und die schweiz: ein wendepunkt f\u00fcr europ\u00e4ische it-strategien?\" data-id=\"3727\"  data-category=\"allgemein gesellschaft\" data-post_tag=\"datenbanken datenschutz digitales eigentum eu-gesetze europa\">\n\t\t\t\t\t\t\t<div class=\"dpt-entry-wrapper\"><div class=\"dpt-featured-content\"><div class=\"dpt-permalink\"><a href=\"https:\/\/www.markus-schall.de\/fr\/2025\/11\/cloud-act-souverainete-des-donnees-et-la-suisse-un-tournant-pour-les-strategies-informatiques-europeennes\/\" class=\"dpt-permalink\"><span class=\"screen-reader-text\">CLOUD-Act, souverainet\u00e9 des donn\u00e9es et la Suisse : un tournant pour les strat\u00e9gies informatiques europ\u00e9ennes ?<\/span><\/a><\/div><div class=\"dpt-thumbnail\"><div class=\"dpt-thumbnail-inner\"><img width=\"1024\" height=\"683\" class=\"attachment-full size-full\" alt=\"Que signifie la r\u00e9solution suisse sur le cloud pour l&#039;Europe ?\" context=\"dpt\" data-dpt-src=\"https:\/\/www.markus-schall.de\/wp-content\/uploads\/schweiz-cloud-resolution-eu.jpg\" data-dpt-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-dpt-srcset=\"https:\/\/www.markus-schall.de\/wp-content\/uploads\/schweiz-cloud-resolution-eu.jpg 1024w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/schweiz-cloud-resolution-eu-300x200.jpg 300w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/schweiz-cloud-resolution-eu-768x512.jpg 768w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/schweiz-cloud-resolution-eu-18x12.jpg 18w\" \/><\/div><span class=\"dpt-thumbnail-aspect-ratio\" style=\"padding-top: 75%\"><\/span><\/div><\/div><div class=\"sub-entry\"><h3 class=\"dpt-title\"><a class=\"dpt-title-link\" href=\"https:\/\/www.markus-schall.de\/fr\/2025\/11\/cloud-act-souverainete-des-donnees-et-la-suisse-un-tournant-pour-les-strategies-informatiques-europeennes\/\" rel=\"bookmark\">CLOUD-Act, souverainet\u00e9 des donn\u00e9es et la Suisse : un tournant pour les strat\u00e9gies informatiques europ\u00e9ennes ?<\/a><\/h3><\/div><\/div>\n\t\t\t\t\t\t<\/div><!-- .dpt-entry -->\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"dpt-entry has-thumbnail\" data-title=\"dauerkrise als normalzustand: wie narrative unsere wahrnehmung verzerren\" data-id=\"3840\"  data-category=\"allgemein b\u00fccher gesellschaft\" data-post_tag=\"buch deutschland energiepolitik erfahrungen europa krisen meinungsfreiheit pers\u00f6nlichkeitsentwicklung\">\n\t\t\t\t\t\t\t<div class=\"dpt-entry-wrapper\"><div class=\"dpt-featured-content\"><div class=\"dpt-permalink\"><a href=\"https:\/\/www.markus-schall.de\/fr\/2025\/12\/la-crise-permanente-comme-etat-normal-comment-les-narratifs-deforment-notre-perception\/\" class=\"dpt-permalink\"><span class=\"screen-reader-text\">La crise permanente comme \u00e9tat normal : comment les r\u00e9cits d\u00e9forment notre perception<\/span><\/a><\/div><div class=\"dpt-thumbnail\"><div class=\"dpt-thumbnail-inner\"><img width=\"1024\" height=\"683\" class=\"attachment-full size-full\" alt=\"Crise permanente, narrative\" context=\"dpt\" data-dpt-src=\"https:\/\/www.markus-schall.de\/wp-content\/uploads\/dauerkrise-narrative.jpg\" data-dpt-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-dpt-srcset=\"https:\/\/www.markus-schall.de\/wp-content\/uploads\/dauerkrise-narrative.jpg 1024w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/dauerkrise-narrative-300x200.jpg 300w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/dauerkrise-narrative-768x512.jpg 768w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/dauerkrise-narrative-18x12.jpg 18w\" \/><\/div><span class=\"dpt-thumbnail-aspect-ratio\" style=\"padding-top: 75%\"><\/span><\/div><\/div><div class=\"sub-entry\"><h3 class=\"dpt-title\"><a class=\"dpt-title-link\" href=\"https:\/\/www.markus-schall.de\/fr\/2025\/12\/la-crise-permanente-comme-etat-normal-comment-les-narratifs-deforment-notre-perception\/\" rel=\"bookmark\">La crise permanente comme \u00e9tat normal : comment les r\u00e9cits d\u00e9forment notre perception<\/a><\/h3><\/div><\/div>\n\t\t\t\t\t\t<\/div><!-- .dpt-entry -->\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"dpt-entry has-thumbnail\" data-title=\"vom content zur substanz: wie digitale systeme entstehen, die nicht kopierbar sind\" data-id=\"5899\"  data-category=\"allgemein b\u00fccher gesellschaft tipps &amp; anleitungen\" data-post_tag=\"buch datenlogik denkmodelle digitales eigentum erfahrungen k\u00fcnstliche intelligenz prozesse publishing ratgeber\">\n\t\t\t\t\t\t\t<div class=\"dpt-entry-wrapper\"><div class=\"dpt-featured-content\"><div class=\"dpt-permalink\"><a href=\"https:\/\/www.markus-schall.de\/fr\/2026\/04\/du-contenu-a-la-substance-comment-des-systemes-numeriques-qui-ne-peuvent-pas-etre-copies-sont-crees\/\" class=\"dpt-permalink\"><span class=\"screen-reader-text\">Du contenu \u00e0 la substance : comment des syst\u00e8mes num\u00e9riques qui ne peuvent pas \u00eatre copi\u00e9s voient le jour<\/span><\/a><\/div><div class=\"dpt-thumbnail\"><div class=\"dpt-thumbnail-inner\"><img width=\"1024\" height=\"682\" class=\"attachment-full size-full\" alt=\"Un syst\u00e8me plut\u00f4t qu&#039;un contenu unique\" context=\"dpt\" data-dpt-src=\"https:\/\/www.markus-schall.de\/wp-content\/uploads\/Organische-Reichweite.jpg\" data-dpt-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-dpt-srcset=\"https:\/\/www.markus-schall.de\/wp-content\/uploads\/Organische-Reichweite.jpg 1024w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/Organische-Reichweite-300x200.jpg 300w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/Organische-Reichweite-768x512.jpg 768w, https:\/\/www.markus-schall.de\/wp-content\/uploads\/Organische-Reichweite-18x12.jpg 18w\" \/><\/div><span class=\"dpt-thumbnail-aspect-ratio\" style=\"padding-top: 75%\"><\/span><\/div><\/div><div class=\"sub-entry\"><h3 class=\"dpt-title\"><a class=\"dpt-title-link\" href=\"https:\/\/www.markus-schall.de\/fr\/2026\/04\/du-contenu-a-la-substance-comment-des-systemes-numeriques-qui-ne-peuvent-pas-etre-copies-sont-crees\/\" rel=\"bookmark\">Du contenu \u00e0 la substance : comment des syst\u00e8mes num\u00e9riques qui ne peuvent pas \u00eatre copi\u00e9s voient le jour<\/a><\/h3><\/div><\/div>\n\t\t\t\t\t\t<\/div><!-- .dpt-entry -->\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n<hr \/>","protected":false},"excerpt":{"rendered":"<p>Consid\u00e9rations sur un \u00e9ventuel retour de la conscription Une sorte d'essai de M. von L'oreot sur un \u00e9ventuel cas de tension.<\/p>","protected":false},"author":1,"featured_media":3019,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":109,"footnotes":""},"categories":[235,1,466,472],"tags":[480,458,482,426,429,484],"class_list":["post-3010","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-stories-humor","category-allgemein","category-gesellschaft","category-kunst-kultur","tag-deutschland","tag-erfahrungen","tag-geopolitik","tag-krisen","tag-persoenlichkeitsentwicklung","tag-sicherheitspolitik"],"_links":{"self":[{"href":"https:\/\/www.markus-schall.de\/fr\/wp-json\/wp\/v2\/posts\/3010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.markus-schall.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.markus-schall.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.markus-schall.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.markus-schall.de\/fr\/wp-json\/wp\/v2\/comments?post=3010"}],"version-history":[{"count":46,"href":"https:\/\/www.markus-schall.de\/fr\/wp-json\/wp\/v2\/posts\/3010\/revisions"}],"predecessor-version":[{"id":5931,"href":"https:\/\/www.markus-schall.de\/fr\/wp-json\/wp\/v2\/posts\/3010\/revisions\/5931"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.markus-schall.de\/fr\/wp-json\/wp\/v2\/media\/3019"}],"wp:attachment":[{"href":"https:\/\/www.markus-schall.de\/fr\/wp-json\/wp\/v2\/media?parent=3010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.markus-schall.de\/fr\/wp-json\/wp\/v2\/categories?post=3010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.markus-schall.de\/fr\/wp-json\/wp\/v2\/tags?post=3010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}